{"id":2871,"date":"2022-11-22T10:46:25","date_gmt":"2023-12-01T14:53:00","guid":{"rendered":""},"modified":"2025-12-01T22:33:01","modified_gmt":"2025-12-01T21:33:01","slug":"ecosistema-de-emprendimiento-barranqueros-utp","status":"publish","type":"post","link":"https:\/\/vicerrectorias.utp.edu.co\/viie\/ecosistema-de-emprendimiento-barranqueros-utp\/","title":{"rendered":"Ecosistema de Emprendimiento Barranqueros UTP"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img decoding=\"async\" src=\"https:\/\/media2.utp.edu.co\/imagenes\/Banner_barranqueros.png\" alt=\"\" style=\"width:897px;height:280px\"\/><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"357\" src=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/DSC02892.-1-1024x357.jpg\" alt=\"\" class=\"wp-image-22365\" style=\"width:861px;height:268px\" srcset=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/DSC02892.-1-1024x357.jpg 1024w, https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/DSC02892.-1-300x105.jpg 300w, https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/DSC02892.-1-768x268.jpg 768w, https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/DSC02892.-1-1536x535.jpg 1536w, https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/DSC02892.-1-2048x714.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-center\"><span class=\"post-content__span\"> <\/p>\n\n\n\n<div class=\"alignnormal\"><div id=\"metaslider-id-17647\" style=\"width: 100%; margin: 0 auto;\" class=\"ml-slider-3-109-0 metaslider metaslider-flex metaslider-17647 ml-slider hide-arrows-smartphone has-dots-nav has-carousel-mode ms-theme-default\" role=\"region\" aria-label=\"Barranquero UTP\" data-height=\"350\" data-width=\"350\">\n    <div id=\"metaslider_container_17647\">\n        <div id=\"metaslider_17647\">\n            <ul class='slides'>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17649 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-12-12 15:43:46\" data-filename=\"imagen1-1-350x350.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/imagen1-1-350x350.png\" height=\"350\" width=\"350\" alt=\"\" class=\"slider-17647 slide-17649 msDefaultImage\" title=\"imagen1\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17651 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-12-12 15:44:40\" data-filename=\"imagen3-1-350x350.jpeg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/imagen3-1-350x350.jpeg\" height=\"350\" width=\"350\" alt=\"\" class=\"slider-17647 slide-17651 msDefaultImage\" title=\"imagen3\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17653 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-12-12 15:45:02\" data-filename=\"imagen2-1-350x350.jpeg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/imagen2-1-350x350.jpeg\" height=\"350\" width=\"350\" alt=\"\" class=\"slider-17647 slide-17653 msDefaultImage\" title=\"imagen2\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17655 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-12-12 15:45:32\" data-filename=\"imagen4-1-350x350.jpeg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/imagen4-1-350x350.jpeg\" height=\"350\" width=\"350\" alt=\"\" class=\"slider-17647 slide-17655 msDefaultImage\" title=\"imagen4\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17769 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-12-13 16:36:59\" data-filename=\"IMG_4033-350x350.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/IMG_4033-350x350.jpg\" height=\"350\" width=\"350\" alt=\"\" class=\"slider-17647 slide-17769 msDefaultImage\" title=\"IMG_4033\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17771 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-12-13 16:37:11\" data-filename=\"IMG_4209-scaled-350x350.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/IMG_4209-scaled-350x350.jpg\" height=\"350\" width=\"350\" alt=\"\" class=\"slider-17647 slide-17771 msDefaultImage\" title=\"IMG_4209\" \/><\/li>\n            <\/ul>\n        <\/div>\n        \n    <\/div>\n<\/div><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img decoding=\"async\" src=\"https:\/\/media2.utp.edu.co\/imagenes\/Texto%20Bienvenida.png\" alt=\"\" style=\"width:779px;height:132px\"\/><\/figure>\n<\/div>\n\n\n<p><span class=\"post-content__span\"> <\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/sobre-nosotros\/\">Sobre Nosotros<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-text-align-center wp-element-button\" href=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/ruta-academica-de-emprendimiento-barranqueros-utp\/\">Ruta Acad\u00e9mica<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/ruta-de-acompanamiento-emprendedores-barranquero-utp\/\">Ruta de Acompa\u00f1amiento Emprendedores<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p><span class=\"post-content__span\"> <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"150\" src=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/6-3-1024x150.png\" alt=\"\" class=\"wp-image-13093\" srcset=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/6-3-1024x150.png 1024w, https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/6-3-300x44.png 300w, https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/6-3-768x113.png 768w, https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/6-3-1536x226.png 1536w, https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/6-3.png 1545w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p><span class=\"post-content__span\"> <\/p>\n\n\n\n<p style=\"font-size:16px;font-style:normal;font-weight:400\">Este espacio est\u00e1 dedicado para que te enteres de todos los eventos que tenemos disponibles para ti. Si quieres estar actualizado en los eventos, a\u00f1ade nuestro calendario al tuyo para que no te pierdas nada<\/p>\n\n\n\n<p class=\"has-text-align-center\"><span class=\"post-content__span\"> <a href=\"https:\/\/calendar.google.com\/calendar\/u\/0?cid=Y18ydDJsMjJraXVzM2p2NXZnMTQ1ZDlkMHE1b0Bncm91cC5jYWxlbmRhci5nb29nbGUuY29t\">https:\/\/calendar.google.com\/calendar\/u\/0?cid=Y18ydDJsMjJraXVzM2p2NXZnMTQ1ZDlkMHE1b0Bncm91cC5jYWxlbmRhci5nb29nbGUY29t<\/a><\/p>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/calendar.google.com\/calendar\/embed?src=c_2t2l22kius3jv5vg145d9d0q5o%40group.calendar.google.com&#038;ctz=America%2FBogota\" style=\"border: 0\" width=\"800\" height=\"600\" frameborder=\"0\" scrolling=\"no\"><\/iframe>\n\n\n\n<p><span class=\"post-content__span\"> <\/p>\n\n\n\n<p class=\"has-text-align-center\" style=\"font-size:16px;font-style:normal;font-weight:400\">Ingresa a este link para enterarte de las convocatorias externas que la Vicerrector\u00eda de Investigaci\u00f3n, Innovaci\u00f3n y Extensi\u00f3n trae para ti.<\/p>\n\n\n\n<p class=\"has-text-align-center\" style=\"font-size:20px;font-style:normal;font-weight:400\"><a href=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/sin-categoria\/convocatorias-externas\/\">https:\/\/vicerrectorias.utp.edu.co\/viie\/sin-categoria\/convocatorias-externas\/<\/a><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"150\" src=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/5-3-1024x150.png\" alt=\"\" class=\"wp-image-13092\" srcset=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/5-3-1024x150.png 1024w, https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/5-3-300x44.png 300w, https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/5-3-768x112.png 768w, https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/5-3-1536x225.png 1536w, https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/5-3.png 1545w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p><span class=\"post-content__span\"> <\/p>\n\n\n\n<div class=\"alignnormal\"><div id=\"metaslider-id-17660\" style=\"width: 100%; margin: 0 auto;\" class=\"ml-slider-3-109-0 metaslider metaslider-flex metaslider-17660 ml-slider hide-arrows-smartphone has-dots-nav has-carousel-mode ms-theme-default\" role=\"region\" aria-label=\"ALIADOS BARRANQUEROS\" data-height=\"250\" data-width=\"250\">\n    <div id=\"metaslider_container_17660\">\n        <div id=\"metaslider_17660\">\n            <ul class='slides'>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17663 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-12-12 16:01:35\" data-filename=\"Diseno-sin-titulo-11.png\" data-slide-type=\"image\"><a href=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/cemprende\/\" target=\"_self\" aria-label=\"Ver detalles de la diapositiva\" class=\"metaslider_image_link\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/Diseno-sin-titulo-11.png\" height=\"250\" width=\"250\" alt=\"\" class=\"slider-17660 slide-17663 msDefaultImage\" title=\"Dise\u00f1o sin t\u00edtulo (11)\" \/><\/a><div class=\"caption-wrap\"><div class=\"caption\"><div style=\"text-align:center;\"><span style=\"color:rgb(255,255,255);\"><a style=\"color:rgb(255,255,255);\" href=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/cemprende\/\">CEMPTENDE<\/a><\/span><\/div><\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17669 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-12-12 16:12:56\" data-filename=\"6f43b7993201bd36bacc611dd9aa947b-250x250.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/6f43b7993201bd36bacc611dd9aa947b-250x250.jpg\" height=\"250\" width=\"250\" alt=\"\" class=\"slider-17660 slide-17669 msDefaultImage\" title=\"6f43b7993201bd36bacc611dd9aa947b\" \/><div class=\"caption-wrap\"><div class=\"caption\"><div style=\"text-align:center;\"><span style=\"color:rgb(255,255,255);\">WORK - ON<\/span><\/div><\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17671 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-12-12 16:13:40\" data-filename=\"Diseno-sin-titulo-12.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/Diseno-sin-titulo-12.png\" height=\"250\" width=\"250\" alt=\"\" class=\"slider-17660 slide-17671 msDefaultImage\" title=\"Dise\u00f1o sin t\u00edtulo (12)\" \/><div class=\"caption-wrap\"><div class=\"caption\"><div style=\"text-align:center;\"><span style=\"color:rgb(255,255,255);\">ANEIAP<\/span><\/div><\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17673 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-12-12 16:14:23\" data-filename=\"aseutp-transparente-250x250.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/aseutp-transparente-250x250.png\" height=\"250\" width=\"250\" alt=\"\" class=\"slider-17660 slide-17673 msDefaultImage\" title=\"aseutp transparente\" \/><div class=\"caption-wrap\"><div class=\"caption\"><div style=\"text-align:center;\"><span style=\"color:rgb(255,255,255);\">ASEUTP<\/span><\/div><\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17675 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-12-12 16:16:56\" data-filename=\"Diseno-sin-titulo-13.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/Diseno-sin-titulo-13.png\" height=\"250\" width=\"250\" alt=\"\" class=\"slider-17660 slide-17675 msDefaultImage\" title=\"Dise\u00f1o sin t\u00edtulo (13)\" \/><div class=\"caption-wrap\"><div class=\"caption\"><div style=\"text-align:center;\"><span style=\"color:rgb(255,255,255);\">Centro de Apoyo a la Tecnolog\u00eda y la Innovaci\u00f3n<\/span><\/div><\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17677 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-12-12 16:18:04\" data-filename=\"Diseno-sin-titulo-14.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/Diseno-sin-titulo-14.png\" height=\"250\" width=\"250\" alt=\"\" class=\"slider-17660 slide-17677 msDefaultImage\" title=\"Dise\u00f1o sin t\u00edtulo (14)\" \/><div class=\"caption-wrap\"><div class=\"caption\"><div style=\"text-align:center;\"><span style=\"color:rgb(255,255,255);\">INNPULSA<\/span><\/div><\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17680 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-12-12 16:25:20\" data-filename=\"Diseno-sin-titulo-15.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/Diseno-sin-titulo-15.png\" height=\"250\" width=\"250\" alt=\"\" class=\"slider-17660 slide-17680 msDefaultImage\" title=\"Dise\u00f1o sin t\u00edtulo (15)\" \/><div class=\"caption-wrap\"><div class=\"caption\"><div style=\"text-align:center;\"><span style=\"color:rgb(255,255,255);\">Risaralda Emprende<\/span><\/div><\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17682 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-12-12 16:26:03\" data-filename=\"descarga-11-222x222.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/descarga-11-222x222.png\" height=\"250\" width=\"250\" alt=\"\" class=\"slider-17660 slide-17682 msDefaultImage\" title=\"descarga (1)(1)\" \/><div class=\"caption-wrap\"><div class=\"caption\"><div style=\"text-align:center;\"><span style=\"color:rgb(255,255,255);\">SENA<\/span><\/div><\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17684 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-12-12 16:28:19\" data-filename=\"Diseno-sin-titulo-16.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/Diseno-sin-titulo-16.png\" height=\"250\" width=\"250\" alt=\"\" class=\"slider-17660 slide-17684 msDefaultImage\" title=\"Dise\u00f1o sin t\u00edtulo (16)\" \/><div class=\"caption-wrap\"><div class=\"caption\"><div style=\"text-align:center;\"><span style=\"color:rgb(255,255,255);\">The Global Agency<\/span><\/div><\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17686 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-12-12 16:31:17\" data-filename=\"Diseno-sin-titulo-17.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/Diseno-sin-titulo-17.png\" height=\"250\" width=\"250\" alt=\"\" class=\"slider-17660 slide-17686 msDefaultImage\" title=\"Dise\u00f1o sin t\u00edtulo (17)\" \/><div class=\"caption-wrap\"><div class=\"caption\"><div style=\"text-align:center;\"><span style=\"color:rgb(255,255,255);\">Red Universitaria de Emprendimiento\u00a0<\/span><\/div><\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17688 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-12-12 16:32:23\" data-filename=\"Diseno-sin-titulo-18.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/Diseno-sin-titulo-18.png\" height=\"250\" width=\"250\" alt=\"\" class=\"slider-17660 slide-17688 msDefaultImage\" title=\"Dise\u00f1o sin t\u00edtulo (18)\" \/><div class=\"caption-wrap\"><div class=\"caption\"><div style=\"text-align:center;\"><span style=\"color:rgb(255,255,255);\">FUNDACI\u00d3N Sembrar FUTURO<\/span><\/div><\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17690 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-12-12 16:34:37\" data-filename=\"e0d716_130b904f73fe4e99893a6bb16472bb1c_mv2-250x250.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/e0d716_130b904f73fe4e99893a6bb16472bb1c_mv2-250x250.png\" height=\"250\" width=\"250\" alt=\"\" class=\"slider-17660 slide-17690 msDefaultImage\" title=\"e0d716_130b904f73fe4e99893a6bb16472bb1c_mv2\" \/><div class=\"caption-wrap\"><div class=\"caption\"><div style=\"text-align:center;\"><span style=\"color:rgb(255,255,255);\">AMBOC\u00a0<\/span><\/div>\n<div style=\"text-align:center;\"><span style=\"color:rgb(255,255,255);\">CONSULTORIA AMBIENTAL Y OBRAS CIVILES<\/span><\/div><\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17692 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-12-12 16:35:51\" data-filename=\"Diseno-sin-titulo-19.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/Diseno-sin-titulo-19.png\" height=\"250\" width=\"250\" alt=\"\" class=\"slider-17660 slide-17692 msDefaultImage\" title=\"Dise\u00f1o sin t\u00edtulo (19)\" \/><div class=\"caption-wrap\"><div class=\"caption\"><div style=\"text-align:center;\"><span style=\"color:rgb(255,255,255);\">FundaTIC<\/span><\/div><\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17694 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-12-12 16:36:29\" data-filename=\"Diseno-sin-titulo-20.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/Diseno-sin-titulo-20.png\" height=\"250\" width=\"250\" alt=\"\" class=\"slider-17660 slide-17694 msDefaultImage\" title=\"Dise\u00f1o sin t\u00edtulo (20)\" \/><div class=\"caption-wrap\"><div class=\"caption\"><div style=\"text-align:center;\"><span style=\"color:rgb(255,255,255);\">Somos so\u00f1adores, somos emprendedores<\/span><\/div><\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17696 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-12-12 17:01:04\" data-filename=\"Diseno-sin-titulo-21.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/Diseno-sin-titulo-21.png\" height=\"250\" width=\"250\" alt=\"\" class=\"slider-17660 slide-17696 msDefaultImage\" title=\"Dise\u00f1o sin t\u00edtulo (21)\" \/><div class=\"caption-wrap\"><div class=\"caption\"><div style=\"text-align:center;\"><span style=\"color:rgb(255,255,255);\">Ejemprende<\/span><\/div><\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17698 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-12-12 17:01:39\" data-filename=\"Diseno-sin-titulo-22.png\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/Diseno-sin-titulo-22.png\" height=\"250\" width=\"250\" alt=\"\" class=\"slider-17660 slide-17698 msDefaultImage\" title=\"Dise\u00f1o sin t\u00edtulo (22)\" \/><div class=\"caption-wrap\"><div class=\"caption\"><div style=\"text-align:center;\"><span style=\"color:rgb(255,255,255);\">ParqueSoft<\/span><\/div><\/div><\/div><\/li>\n            <\/ul>\n        <\/div>\n        \n    <\/div>\n<\/div><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"150\" src=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/7-2-1024x150.png\" alt=\"\" class=\"wp-image-13099\" srcset=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/7-2-1024x150.png 1024w, https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/7-2-300x44.png 300w, https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/7-2-768x113.png 768w, https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/7-2-1536x226.png 1536w, https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/7-2.png 1545w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/ir-24-1024x576.png\" alt=\"\" class=\"wp-image-17744\" style=\"width:628px;height:auto\" srcset=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/ir-24-1024x576.png 1024w, https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/ir-24-300x169.png 300w, https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/ir-24-768x432.png 768w, https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/ir-24.png 1366w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/ir-25-1024x576.png\" alt=\"\" class=\"wp-image-22367\" srcset=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/ir-25-1024x576.png 1024w, https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/ir-25-300x169.png 300w, https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/ir-25-768x432.png 768w, https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/ir-25.png 1366w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Este espacio est\u00e1 dedicado para que te enteres de todos los eventos que tenemos disponibles para ti. Si quieres estar actualizado en los eventos, a\u00f1ade nuestro calendario al tuyo para [&#8230;]<\/p>\n","protected":false},"author":0,"featured_media":22365,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2871","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-json\/wp\/v2\/posts\/2871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-json\/wp\/v2\/comments?post=2871"}],"version-history":[{"count":70,"href":"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-json\/wp\/v2\/posts\/2871\/revisions"}],"predecessor-version":[{"id":22368,"href":"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-json\/wp\/v2\/posts\/2871\/revisions\/22368"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-json\/wp\/v2\/media\/22365"}],"wp:attachment":[{"href":"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-json\/wp\/v2\/media?parent=2871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-json\/wp\/v2\/categories?post=2871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-json\/wp\/v2\/tags?post=2871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}