{"id":24089,"date":"2026-06-09T00:00:00","date_gmt":"2026-06-08T22:00:00","guid":{"rendered":"https:\/\/vicerrectorias.utp.edu.co\/viie\/?p=24089"},"modified":"2026-07-09T16:52:50","modified_gmt":"2026-07-09T14:52:50","slug":"convocatoria-para-financiar-propuestas-de-solucion-a-retos-empresariales-2026","status":"publish","type":"post","link":"https:\/\/vicerrectorias.utp.edu.co\/viie\/convocatoria-para-financiar-propuestas-de-solucion-a-retos-empresariales-2026\/","title":{"rendered":"CONVOCATORIA PARA FINANCIAR PROPUESTAS DE SOLUCI\u00d3N A RETOS EMPRESARIALES 2026"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"256\" src=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/Banner-Para-LinkedIn-Profesional-Analista-En-Ciberseguridad-Moderno-Azul-Y-Blanco-6-1024x256.png\" alt=\"\" class=\"wp-image-24090\" srcset=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/Banner-Para-LinkedIn-Profesional-Analista-En-Ciberseguridad-Moderno-Azul-Y-Blanco-6-1024x256.png 1024w, https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/Banner-Para-LinkedIn-Profesional-Analista-En-Ciberseguridad-Moderno-Azul-Y-Blanco-6-300x75.png 300w, https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/Banner-Para-LinkedIn-Profesional-Analista-En-Ciberseguridad-Moderno-Azul-Y-Blanco-6-768x192.png 768w, https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/Banner-Para-LinkedIn-Profesional-Analista-En-Ciberseguridad-Moderno-Azul-Y-Blanco-6-1536x384.png 1536w, https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/Banner-Para-LinkedIn-Profesional-Analista-En-Ciberseguridad-Moderno-Azul-Y-Blanco-6.png 1584w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p><span class=\"post-content__span\"> <\/p>\n\n\n\n<p><span class=\"post-content__span\"> <\/p>\n\n\n\n<p><span class=\"post-content__span\"> <\/p>\n\n\n\n<p class=\"has-text-align-center\"><span class=\"post-content__span\"> <em>La Universidad Tecnol\u00f3gica de Pereira, en el marco del fortalecimiento de la relaci\u00f3n Universidad \u2013 Empresa y en cumplimiento del pilar de Creaci\u00f3n, Gesti\u00f3n y Transferencia de Conocimiento del Plan de Desarrollo Institucional 2020 \u2013 2028, habilita la convocatoria para financiar propuestas de soluci\u00f3n a retos empresariales previamente definidos en articulaci\u00f3n con actores del sector productivo del departamento de Risaralda.<\/em><br><\/p>\n\n\n\n<p><span class=\"post-content__span\"> <\/p>\n\n\n\n<p><span class=\"post-content__span\"> <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/Diseno-sin-titulo-6-1-819x1024.png\" alt=\"\" class=\"wp-image-24092\" srcset=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/Diseno-sin-titulo-6-1-819x1024.png 819w, https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/Diseno-sin-titulo-6-1-240x300.png 240w, https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/Diseno-sin-titulo-6-1-768x960.png 768w, https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/Diseno-sin-titulo-6-1.png 1080w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/figure>\n<\/div>\n\n\n<p><span class=\"post-content__span\"> <\/p>\n\n\n\n<p><span class=\"post-content__span\"> <\/p>\n\n\n\n<p><span class=\"post-content__span\"> <\/p>\n\n\n\n<p><span class=\"post-content__span\"> Los retos describen una problem\u00e1tica o necesidad identificada por las empresas o agremiaciones, y constituyen el punto de partida para que los semilleros de investigaci\u00f3n adscritos a grupos de investigaci\u00f3n registrados en la Vicerrector\u00eda de Investigaciones, Innovaci\u00f3n y Extensi\u00f3n, que hayan participado en la Convocatoria 957 de MinCiencias (2024),<strong> <\/strong>propongan soluciones innovadoras, viables y pertinentes desde la investigaci\u00f3n formativa.&nbsp;<br><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-0f4f5c0d7fec1821dbc2ccf2694db658\" style=\"color:#002460\"><strong>OBJETIVO<\/strong><\/h2>\n\n\n\n<p><span class=\"post-content__span\"> Fomentar la articulaci\u00f3n de los semilleros de investigaci\u00f3n de la Universidad Tecnol\u00f3gica de Pereira, con el sector productivo regional, mediante el desarrollo de propuestas de soluci\u00f3n a retos empresariales, en el marco del proceso de investigaci\u00f3n formativa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-ded768c7dd4e9a60be315be58bc6464d\" style=\"color:#002460\"><strong>DIRIGIDO A<\/strong><\/h2>\n\n\n\n<p><span class=\"post-content__span\"> Semilleros de investigaci\u00f3n de la Universidad Tecnol\u00f3gica de Pereira adscritos a grupos de investigaci\u00f3n que hayan participado en la Convocatoria 957 de 2024 para la medici\u00f3n de grupos y reconocimiento de investigadores de MinCiencias.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-689627fc65828f7f899c2081e00cfa1c\" style=\"color:#002460\"><strong>RETOS EMPRESARIALES<\/strong><\/h2>\n\n\n\n<p><span class=\"post-content__span\"> Los interesados en participar en la presente convocatoria deber\u00e1n remitir una propuesta de soluci\u00f3n a alguno de los retos que ser\u00e1n previamente formulados con las empresas y agremiaciones interesadas.<\/p>\n\n\n\n<p><span class=\"post-content__span\"> Se entregar\u00e1 la respectiva ficha t\u00e9cnica del reto.<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/Fichas-para-convocatoria-retos-empresariales-Mayo-2026-GTIE-1-39.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incrustado de Fichas para convocatoria retos empresariales Mayo 2026 GTIE-1-39.\"><\/object><a id=\"wp-block-file--media-bf38257b-c9ea-4430-8617-77ac35981589\" href=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/Fichas-para-convocatoria-retos-empresariales-Mayo-2026-GTIE-1-39.pdf\">Fichas para convocatoria retos empresariales Mayo 2026 GTIE-1-39<\/a><a href=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/Fichas-para-convocatoria-retos-empresariales-Mayo-2026-GTIE-1-39.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-bf38257b-c9ea-4430-8617-77ac35981589\">Descarga<\/a><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-37ee65a7d49af001c71c661557641ec5\" style=\"color:#002460\"><strong>REQUISITOS&nbsp;<\/strong><\/h2>\n\n\n\n<p><span class=\"post-content__span\"> Con el fin de garantizar la pertinencia y viabilidad de las propuestas presentadas, los equipos interesados en participar deber\u00e1n cumplir los <strong>Requisitos habilitantes generales<\/strong>, que definen qui\u00e9nes pueden participar y bajo qu\u00e9 condiciones institucionales, y los <strong>Requisitos habilitantes espec\u00edficos<\/strong>, que detallan los criterios t\u00e9cnicos y documentales m\u00ednimos para que las propuestas sean evaluadas.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Requisitos Habilitantes Generales:<\/strong><\/li>\n<\/ol>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El semillero de investigaci\u00f3n deber\u00e1 estar en estado activo a la fecha de apertura de la presente convocatoria, y contar con un tiempo de creaci\u00f3n o reactivaci\u00f3n m\u00ednima de seis meses.<\/li>\n\n\n\n<li>El semillero de investigaci\u00f3n deber\u00e1 estar adscrito a un grupo de investigaci\u00f3n registrado en la Vicerrector\u00eda de Investigaciones, Innovaci\u00f3n y Extensi\u00f3n, que haya participado en la Convocatoria 957 de 2024 de Medici\u00f3n de Grupos y Reconocimiento de Investigadores.<\/li>\n\n\n\n<li>El grupo de investigaci\u00f3n y los integrantes de la propuesta deber\u00e1n tener actualizada la informaci\u00f3n en el CvLAC y en el GrupLAC con corte a 30 de noviembre de 2025.&nbsp;<\/li>\n\n\n\n<li>Los estudiantes vinculados a la propuesta deber\u00e1n cumplir con los siguientes requisitos:<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ser estudiante activo acad\u00e9mica y financieramente para el per\u00edodo acad\u00e9mico 2026 &#8211; 2.<\/li>\n\n\n\n<li>Debe haber cursado m\u00ednimo el <strong>50% <\/strong>de los cr\u00e9ditos del programa acad\u00e9mico que est\u00e1 realizando, para el per\u00edodo <strong>2026 &#8211; 1.<\/strong>\n<ul class=\"wp-block-list\">\n<li>Tener un promedio acumulado del \u00faltimo per\u00edodo acad\u00e9mico registrado igual o superior a 3,5<\/li>\n\n\n\n<li>Los equipos podr\u00e1n vincular estudiantes de posgrado (especializaci\u00f3n, maestr\u00eda o doctorado) como apoyo t\u00e9cnico o metodol\u00f3gico en el desarrollo de la propuesta. Su participaci\u00f3n ser\u00e1 de car\u00e1cter complementario y no sustituye el rol protag\u00f3nico de los estudiantes de pregrado vinculados al semillero.&nbsp;<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La propuesta presentada deber\u00e1 contar con un tutor, docente de planta o transitorio, vinculado al semillero de investigaci\u00f3n o al grupo de investigaci\u00f3n en el cual el semillero est\u00e1 adscrito<strong>.<\/strong><\/li>\n\n\n\n<li>Todos los integrantes del equipo (estudiantes y docente tutor) deber\u00e1n contar con disponibilidad de tiempo para desarrollar el prototipo que da soluci\u00f3n al reto en los plazos establecidos, y participar activamente en las actividades programadas, incluyendo reuniones de avance, espacios de acompa\u00f1amiento y la socializaci\u00f3n de los resultados.<\/li>\n<\/ul>\n\n\n\n<p><span class=\"post-content__span\"> <strong>NOTA 1: <\/strong>Para la presente convocatoria, se entiende por <strong>prototipo <\/strong>la representaci\u00f3n tangible o funcional de una idea, concepto, producto, servicio o proceso, que permite validar, evaluar y mejorar su viabilidad t\u00e9cnica, comercial o social antes de su implementaci\u00f3n definitiva. Puede adoptar m\u00faltiples formas, desde artefactos f\u00edsicos y dise\u00f1os digitales hasta metodolog\u00edas, modelos operativos, diagramas de flujo o simulaciones, seg\u00fan la naturaleza del problema que se busca resolver.<\/p>\n\n\n\n<ol start=\"2\" class=\"wp-block-list\">\n<li><strong>Requisitos Habilitantes Espec\u00edficos:<\/strong><\/li>\n<\/ol>\n\n\n\n<p><span class=\"post-content__span\"> La propuesta presentada por el equipo participante deber\u00e1 consolidarse en un \u00fanico documento en formato PDF, y radicarse en el correo electr\u00f3nico <a href=\"mailto:lazos@utp.edu.co\"><strong>lazos@utp.edu.co<\/strong><\/a> (<em>el cual ha sido dispuesto institucionalmente para la recepci\u00f3n oficial de propuestas en el marco de esta convocatoria<\/em>), dirigida a la Vicerrector\u00eda de Investigaciones, Innovaci\u00f3n y Extensi\u00f3n a m\u00e1s tardar el&nbsp;<strong>10&nbsp;de julio de 2026 <\/strong>a las<strong> 2:00 P.M<\/strong>. incluyendo los siguientes anexos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Carta de presentaci\u00f3n a la convocatoria firmada por el docente tutor responsable de la propuesta con el visto bueno del director del grupo de investigaci\u00f3n al que est\u00e1 adscrito el semillero de investigaci\u00f3n (firma electr\u00f3nica establecida en la Resoluci\u00f3n 5059 del 7 de julio de 2022). (Ver <strong>ANEXO 1<\/strong>).&nbsp;<\/li>\n\n\n\n<li>Ficha de identificaci\u00f3n y certificaci\u00f3n de proyecto en formato PDF, donde se relacionen los participantes: docente tutor y los estudiantes de pregrado que cuenten con vinculaci\u00f3n activa al semillero de investigaci\u00f3n. Se podr\u00e1 contar con un m\u00ednimo de un (1) estudiante y un m\u00e1ximo de tres (3) estudiantes en la propuesta (Se recomienda que el grupo de trabajo sea interdisciplinario) (Ver <strong>ANEXO 2<\/strong>).&nbsp;<\/li>\n\n\n\n<li>Documento t\u00e9cnico de la propuesta de soluci\u00f3n al reto empresarial seleccionado (Ver <strong>ANEXO 3<\/strong>).&nbsp;<\/li>\n\n\n\n<li>Presupuesto de la propuesta en formato de Excel (Ver <strong>ANEXO 4<\/strong>).<\/li>\n<\/ul>\n\n\n\n<p><span class=\"post-content__span\"> Es importante tener en cuenta los siguientes aspectos:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Soluci\u00f3n alineada con el reto planteado por la empresa o agremiaci\u00f3n: <\/strong>La propuesta debe responder de manera clara y directa a la necesidad presentada por la empresa o agremiaci\u00f3n, evidenciando su pertinencia, aplicabilidad e impacto.<\/li>\n<\/ol>\n\n\n\n<ol start=\"2\" class=\"wp-block-list\">\n<li><strong>Participaci\u00f3n activa y colaborativa del equipo: <\/strong>Se debe evidenciar el trabajo conjunto y multidisciplinar de los integrantes en el an\u00e1lisis del reto y la formulaci\u00f3n de la propuesta.<\/li>\n<\/ol>\n\n\n\n<ol start=\"3\" class=\"wp-block-list\">\n<li><strong>Factibilidad t\u00e9cnica del prototipo que da soluci\u00f3n al reto seleccionado: <\/strong>La soluci\u00f3n propuesta debe ser t\u00e9cnicamente factible dentro del tiempo y presupuesto definidos, con una ruta clara hacia su desarrollo funcional.<\/li>\n<\/ol>\n\n\n\n<p><span class=\"post-content__span\"> Las propuestas deber\u00e1n contemplar el desarrollo de soluciones cuyo resultado m\u00ednimo se encuentre en <strong>TRL 3<\/strong>: Prueba experimental de concepto. Esta fase incluye la realizaci\u00f3n de actividades de investigaci\u00f3n y desarrollo (I+D) dentro de las cuales se incluye la realizaci\u00f3n de pruebas anal\u00edticas y pruebas a escala en laboratorio orientadas a demostrar la factibilidad t\u00e9cnica de los conceptos tecnol\u00f3gicos. Esta fase implica la validaci\u00f3n de los componentes de una tecnolog\u00eda o soluci\u00f3n espec\u00edfica, aunque esto no derive en la integraci\u00f3n de todos los componentes en un sistema completo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-818e178b22f3a5a4ba8ef53ae6a804bc\" style=\"color:#002460\"><strong>PROCEDIMIENTO DE REVISI\u00d3N Y EVALUACI\u00d3N DE PROPUESTAS<\/strong><\/h2>\n\n\n\n<p><span class=\"post-content__span\"> Cada propuesta ser\u00e1 evaluada con base en los siguientes <strong>criterios y puntajes<\/strong>:<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-regular\"><table class=\"has-fixed-layout\"><thead><tr><th><strong>Criterio<\/strong><\/th><th><strong>Puntaje M\u00e1ximo<\/strong><\/th><\/tr><tr><th>Pertinencia y alineaci\u00f3n con el reto planteado<\/th><th>25 puntos<\/th><\/tr><tr><th>Nivel de innovaci\u00f3n y creatividad de la soluci\u00f3n<\/th><th>20 puntos<\/th><\/tr><tr><th>Viabilidad t\u00e9cnica y factibilidad de desarrollo<\/th><th>20 puntos<\/th><\/tr><tr><th>Claridad, coherencia y calidad de la formulaci\u00f3n<\/th><th>15 puntos<\/th><\/tr><tr><th>Aporte a los ODS (Anexo5) y compromiso social<\/th><th>10 puntos<\/th><\/tr><tr><th>Participaci\u00f3n activa e interdisciplinaria del equipo<\/th><th>10 puntos<\/th><\/tr><tr><th><strong>Total<\/strong><\/th><th><strong>100 puntos<\/strong><\/th><\/tr><\/thead><\/table><\/figure>\n\n\n\n<p><span class=\"post-content__span\"> Ver <strong>ANEXO 6 <\/strong>R\u00fabrica de evaluaci\u00f3n<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-671a0c000854384838ef9a000fa37c9e\" style=\"color:#002460\"><strong>CRONOGRAMA<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-table aligncenter\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>Actividad<\/strong><\/td><td><strong>Fecha<\/strong><\/td><\/tr><tr><td>Apertura de la convocatoria y socializaci\u00f3n de los retos por parte de las empresas o agremiaciones<\/td><td><strong>09 de junio de 2026<\/strong><\/td><\/tr><tr><td>Cierre de la convocatoria y radicaci\u00f3n de propuestas ante la Oficina de Gesti\u00f3n de Documentos&nbsp;<\/td><td><strong>10 de julio de 2026&nbsp;<\/strong><strong>hasta las 2:00 p.m.&nbsp;<\/strong><\/td><\/tr><tr><td>Evaluaci\u00f3n y selecci\u00f3n de las propuestas<\/td><td><strong>13 al 17 de julio de 2026<\/strong><\/td><\/tr><tr><td>Publicaci\u00f3n de banco de propuestas elegibles<\/td><td><strong>21 de julio de 2026<\/strong><\/td><\/tr><tr><td>Inicio de ejecuci\u00f3n de propuestas<\/td><td><strong>03 de agosto de 2026<\/strong><\/td><\/tr><tr><td>Socializaci\u00f3n de resultados<\/td><td><strong>Del 23 al 27 de noviembre 2066<\/strong><\/td><\/tr><tr><td>Presentaci\u00f3n de informe final<\/td><td><strong>2 de diciembre 2026<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-9aa07085f88571ae78a675e42464605e\" style=\"color:#002460\"><strong>TIEMPO DE EJECUCI\u00d3N DE LA PROPUESTA<\/strong><\/h2>\n\n\n\n<p><span class=\"post-content__span\"> El tiempo de ejecuci\u00f3n de las propuestas iniciar\u00e1 a partir de la <strong>legalizaci\u00f3n formal del inicio<\/strong>, mediante la firma del acta de inicio y los dem\u00e1s documentos requeridos por parte del equipo de trabajo (estudiantes y docente tutor), y la empresa o agremiaci\u00f3n, y finalizar\u00e1 con la entrega del informe final, con fecha m\u00e1xima el <strong>2 de diciembre de 2026<\/strong>.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Entregables de la convocatoria<\/strong><\/li>\n<\/ol>\n\n\n\n<p><span class=\"post-content__span\"> Los equipos seleccionados deber\u00e1n cumplir con los siguientes entregables:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Socializaci\u00f3n final de soluciones ante empresas\/agremiaciones:<\/strong><\/li>\n<\/ul>\n\n\n\n<p><span class=\"post-content__span\"> Cada equipo deber\u00e1 presentar el prototipo ante la empresa o gremio que formul\u00f3 el reto, as\u00ed como ante la instituci\u00f3n, en un espacio de socializaci\u00f3n de resultados.<br>Plazo m\u00e1ximo para la socializaci\u00f3n: <strong>27 de noviembre de 2026<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Informe final:<\/strong><\/li>\n<\/ul>\n\n\n\n<p><span class=\"post-content__span\"> Documento que detalle el proceso de desarrollo del prototipo, resultados obtenidos, aprendizajes y evidencia de validaci\u00f3n.<\/p>\n\n\n\n<p><span class=\"post-content__span\"> Este documento ser\u00e1 revisado conjuntamente por el tutor del equipo y un representante del \u00e1rea de Gesti\u00f3n Tecnol\u00f3gica de la Vicerrector\u00eda de Investigaciones, Innovaci\u00f3n y Extensi\u00f3n, con el objetivo de verificar el nivel de madurez del prototipo presentado.<br>Plazo m\u00e1ximo para entrega del informe final: <strong>2 de diciembre de 2026<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-c3c5995c644f944e448ad2a91b19b3ac\" style=\"color:#002460\"><strong>FINANCIACI\u00d3N<\/strong><\/h2>\n\n\n\n<p><span class=\"post-content__span\"> El monto m\u00e1ximo de financiaci\u00f3n por propuesta no podr\u00e1 exceder a <strong>Tres Millones de pesos ($3.000.000).&nbsp;<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-902fff41ca84fb927ff9cddcd6a2a5a8\" style=\"color:#002460\"><strong>Rubros Financiables<\/strong><\/h2>\n\n\n\n<p><span class=\"post-content__span\"> En la presente convocatoria se financiar\u00e1n los siguientes rubros con recursos de la Universidad Tecnol\u00f3gica de Pereira:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Compra de materiales e insumos<\/li>\n\n\n\n<li>Este rubro no incluye la adquisici\u00f3n ni el mantenimiento de equipos, herramientas o mobiliario.<\/li>\n\n\n\n<li>Contrataci\u00f3n de monitores<\/li>\n\n\n\n<li>Apoyo t\u00e9cnico especializado (cuando aplique)<\/li>\n<\/ul>\n\n\n\n<p><span class=\"post-content__span\"> La planeaci\u00f3n presupuestal debe ser coherente con los resultados esperados de la propuesta, y el cumplimiento de los objetivos de este; los recursos asignados son intransferibles e inmodificables y deber\u00e1n ser ejecutados en la vigencia 2026, en ning\u00fan caso se aceptar\u00e1n traslados a la vigencia 2027.&nbsp;<\/p>\n\n\n\n<p><span class=\"post-content__span\"> <strong>No se aprobar\u00e1n gastos que se encuentren por fuera de lo anteriormente establecido.<\/strong><\/p>\n\n\n\n<p><span class=\"post-content__span\"> <strong>Rubros no financiables<\/strong><\/p>\n\n\n\n<p><span class=\"post-content__span\"> No ser\u00e1n financiables, entre otros, los siguientes conceptos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pago de publicaciones acad\u00e9micas.&nbsp;<\/li>\n\n\n\n<li>Divulgaci\u00f3n en eventos acad\u00e9micos (ponencias o p\u00f3ster).&nbsp;<\/li>\n\n\n\n<li>Compra de tiquetes.&nbsp;<\/li>\n\n\n\n<li>Suministro de refrigerios.&nbsp;<\/li>\n\n\n\n<li>Alquiler de espacios f\u00edsicos.&nbsp;<\/li>\n\n\n\n<li>Compra de materiales importados.&nbsp;<\/li>\n\n\n\n<li>Compra y\/o mantenimiento de equipos y software.&nbsp;<\/li>\n\n\n\n<li>Compra de muebles y enseres.<\/li>\n\n\n\n<li>No est\u00e1 permitido contratar personal para desarrollar labores administrativas ni contables relacionadas con el proyecto<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-05a5a3f5f9be8d978cfe47d07537151c\" style=\"color:#002460\"><strong>DOCUMENTOS ANEXOS<\/strong><\/h2>\n\n\n\n<p><span class=\"post-content__span\"> <strong>T\u00e9rminos de referencia<\/strong><\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/TDR-retos-empresariales-2026-2-V4.docx.pdf\" type=\"application\/pdf\" style=\"width:100%;height:780px\" aria-label=\"Incrustado de TDR retos empresariales 2026-2 V4.docx.\"><\/object><a id=\"wp-block-file--media-60076076-b2f2-4cb7-a2ea-b09c01ba6639\" href=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/TDR-retos-empresariales-2026-2-V4.docx.pdf\">TDR retos empresariales 2026-2 V4.docx<\/a><a href=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/TDR-retos-empresariales-2026-2-V4.docx.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-60076076-b2f2-4cb7-a2ea-b09c01ba6639\">Descarga<\/a><\/div>\n\n\n\n<p><span class=\"post-content__span\"> <\/p>\n\n\n\n<p><span class=\"post-content__span\"> <\/p>\n\n\n\n<p><span class=\"post-content__span\"> <strong>Acuerdo de consejo acad\u00e9mico No. 27 <\/strong><\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/AcuerdoNo.27CA2026_compressed.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incrustado de Acuerdo+No.+27+CA+2026_compressed.\"><\/object><a id=\"wp-block-file--media-0b32bb1c-781c-4728-8dac-b16c7893e3b8\" href=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/AcuerdoNo.27CA2026_compressed.pdf\">Acuerdo+No.+27+CA+2026_compressed<\/a><a href=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/AcuerdoNo.27CA2026_compressed.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-0b32bb1c-781c-4728-8dac-b16c7893e3b8\">Descarga<\/a><\/div>\n\n\n\n<p><span class=\"post-content__span\"> <\/p>\n\n\n\n<p><span class=\"post-content__span\"> <strong>ADENDA N\u00b0 1. Modificaci\u00f3n del Cronograma Convocatoria para financiar propuestas de soluci\u00f3n a retos empresariales<\/strong><\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/Adenda-N\u00b01.-Modificacion-fecha-de-cierre-CONVOCATORIA-PARA-FINANCIAR-PROPUESTAS-DE-SOLUCION-A-RETOS-EMPRESARIALES-2026-ajustada.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incrustado de Adenda N\u00b01. Modificacion fecha de cierre CONVOCATORIA PARA FINANCIAR PROPUESTAS DE SOLUCI\u00d3N A RETOS EMPRESARIALES 2026 ajustada.\"><\/object><a id=\"wp-block-file--media-71c7a8c5-8fe6-43d9-ab46-91cb6c13068b\" href=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/Adenda-N\u00b01.-Modificacion-fecha-de-cierre-CONVOCATORIA-PARA-FINANCIAR-PROPUESTAS-DE-SOLUCION-A-RETOS-EMPRESARIALES-2026-ajustada.pdf\">Adenda N\u00b01. Modificacion fecha de cierre CONVOCATORIA PARA FINANCIAR PROPUESTAS DE SOLUCI\u00d3N A RETOS EMPRESARIALES 2026 ajustada<\/a><a href=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/Adenda-N\u00b01.-Modificacion-fecha-de-cierre-CONVOCATORIA-PARA-FINANCIAR-PROPUESTAS-DE-SOLUCION-A-RETOS-EMPRESARIALES-2026-ajustada.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-71c7a8c5-8fe6-43d9-ab46-91cb6c13068b\">Descarga<\/a><\/div>\n\n\n\n<p><span class=\"post-content__span\"> <\/p>\n\n\n\n<p><span class=\"post-content__span\"> <strong>Acuerdo No 32 del Consejo Acad\u00e9mico &#8211; aclaraci\u00f3n del acuerdo No. 27<\/strong><\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/Acuerdo-No.-32-CA-2026_0001.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incrustado de Acuerdo No. 32 CA 2026_0001.\"><\/object><a id=\"wp-block-file--media-2e6d86bf-c772-4a52-987c-89f5d2a6a7d1\" href=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/Acuerdo-No.-32-CA-2026_0001.pdf\">Acuerdo No. 32 CA 2026_0001<\/a><a href=\"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-content\/uploads\/sites\/3\/Acuerdo-No.-32-CA-2026_0001.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-2e6d86bf-c772-4a52-987c-89f5d2a6a7d1\">Descarga<\/a><\/div>\n\n\n\n<p><span class=\"post-content__span\"> <\/p>\n\n\n\n<p><span class=\"post-content__span\"> <strong>ANEXO 1:&nbsp;<\/strong><a href=\"https:\/\/docs.google.com\/document\/d\/1_ksxSHbNp1s2O3jdpucwpzhomIsoxuHt\/edit?usp=drive_link&amp;ouid=110379325761109146519&amp;rtpof=true&amp;sd=true\" target=\"_blank\" rel=\"noreferrer noopener\">Modelo deCarta de postulaci\u00f3n a la convocatoria.<\/a><\/p>\n\n\n\n<p><span class=\"post-content__span\"> <strong>ANEXO 2:<\/strong>&nbsp;<a href=\"https:\/\/docs.google.com\/document\/d\/10ku6eN9eFF-6dIPc7eci4vQ6go0m33-X\/edit?usp=drive_link&amp;ouid=110379325761109146519&amp;rtpof=true&amp;sd=true\" target=\"_blank\" rel=\"noreferrer noopener\">Ficha de identificaci\u00f3n proyectos (Relaci\u00f3n de participantes y certificaci\u00f3n de la propuesta).<\/a><\/p>\n\n\n\n<p><span class=\"post-content__span\"> <strong>ANEXO 3<\/strong>:&nbsp;<a href=\"https:\/\/docs.google.com\/document\/d\/1LgYYjuJI7Zz1vhFod9o3gSe3kkPYa3vI\/edit?usp=drive_link&amp;ouid=110379325761109146519&amp;rtpof=true&amp;sd=true\" target=\"_blank\" rel=\"noreferrer noopener\">Documento t\u00e9cnico<\/a><\/p>\n\n\n\n<p><span class=\"post-content__span\"> <strong>ANEXO 4<\/strong>:&nbsp;<a href=\"https:\/\/docs.google.com\/spreadsheets\/d\/1U2Le0fggfnC0CadF9n1UIeLFi515xdtf\/edit?usp=drive_link&amp;ouid=110379325761109146519&amp;rtpof=true&amp;sd=true\" target=\"_blank\" rel=\"noreferrer noopener\">Presupuesto de la propuesta.<\/a><\/p>\n\n\n\n<p><span class=\"post-content__span\"> <strong>ANEXO 5<\/strong>:&nbsp;<a href=\"https:\/\/drive.google.com\/file\/d\/1rN9h7kmNbc5TmaVeckLm1GOMN8n2_k_Y\/view?usp=drive_link\" target=\"_blank\" rel=\"noreferrer noopener\">ODS \u2013 Objetivos de Desarrollo Sostenible.<\/a><\/p>\n\n\n\n<p><span class=\"post-content__span\"> <strong>ANEXO 6<\/strong>: <a href=\"https:\/\/drive.google.com\/file\/d\/1ONyfzExXNrIz3G_i1t-4GDbc997_aNa3\/view?usp=drive_link\" target=\"_blank\" rel=\"noreferrer noopener\">R\u00fabrica de evaluaci\u00f3n<\/a><\/p>\n\n\n\n<p><span class=\"post-content__span\"> <\/p>\n\n\n\n<p><span class=\"post-content__span\"> <\/p>\n\n\n\n<p class=\"has-text-align-center\"><span class=\"post-content__span\"> <strong>M\u00c1S INFORMACI\u00d3N<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\"><span class=\"post-content__span\"> Vicerrector\u00eda de Investigaciones, Innovaci\u00f3n y Extensi\u00f3n<\/p>\n\n\n\n<p class=\"has-text-align-center\"><span class=\"post-content__span\"> <strong>Email:&nbsp;<\/strong><a href=\"mailto:innovacionutp@utp.edu.co\">innovacionutp@utp.edu.co<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center\"><span class=\"post-content__span\"> Tel\u00e9fono: 3137300 Ext 7351<\/p>\n\n\n\n<p class=\"has-text-align-center\"><span class=\"post-content__span\"> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Universidad Tecnol\u00f3gica de Pereira, en el marco del fortalecimiento de la relaci\u00f3n Universidad \u2013 Empresa y en cumplimiento del pilar de Creaci\u00f3n, Gesti\u00f3n y Transferencia de Conocimiento del Plan [&#8230;]<\/p>\n","protected":false},"author":16,"featured_media":24090,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-24089","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-json\/wp\/v2\/posts\/24089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-json\/wp\/v2\/comments?post=24089"}],"version-history":[{"count":16,"href":"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-json\/wp\/v2\/posts\/24089\/revisions"}],"predecessor-version":[{"id":24447,"href":"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-json\/wp\/v2\/posts\/24089\/revisions\/24447"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-json\/wp\/v2\/media\/24090"}],"wp:attachment":[{"href":"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-json\/wp\/v2\/media?parent=24089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-json\/wp\/v2\/categories?post=24089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vicerrectorias.utp.edu.co\/viie\/wp-json\/wp\/v2\/tags?post=24089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}